{"id":39133,"date":"2025-04-14T17:15:52","date_gmt":"2025-04-14T15:15:52","guid":{"rendered":"https:\/\/www.rodaonline.com\/?p=39133"},"modified":"2025-04-23T09:36:34","modified_gmt":"2025-04-23T07:36:34","slug":"salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino","status":"publish","type":"post","link":"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/","title":{"rendered":"Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10808,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21,1],"tags":[],"class_list":["post-39133","post","type-post","status-publish","format-standard","hentry","category-eventi","category-novita","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d - Roda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d - Roda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/\" \/>\n<meta property=\"og:site_name\" content=\"Roda\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T15:15:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T07:36:34+00:00\" \/>\n<meta name=\"author\" content=\"roda_u\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"roda_u\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/novita\\\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/novita\\\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\\\/\"},\"author\":{\"name\":\"roda_u\",\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/#\\\/schema\\\/person\\\/127511466861ea0a94826191fb005d47\"},\"headline\":\"Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d\",\"datePublished\":\"2025-04-14T15:15:52+00:00\",\"dateModified\":\"2025-04-23T07:36:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/novita\\\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\\\/\"},\"wordCount\":11,\"articleSection\":[\"Eventi\",\"Novit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/novita\\\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\\\/\",\"url\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/novita\\\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\\\/\",\"name\":\"Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d - Roda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/#website\"},\"datePublished\":\"2025-04-14T15:15:52+00:00\",\"dateModified\":\"2025-04-23T07:36:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/#\\\/schema\\\/person\\\/127511466861ea0a94826191fb005d47\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/novita\\\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/\",\"name\":\"Roda\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rodaonline.com\\\/it\\\/#\\\/schema\\\/person\\\/127511466861ea0a94826191fb005d47\",\"name\":\"roda_u\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d - Roda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/","og_locale":"it_IT","og_type":"article","og_title":"Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d - Roda","og_url":"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/","og_site_name":"Roda","article_published_time":"2025-04-14T15:15:52+00:00","article_modified_time":"2025-04-23T07:36:34+00:00","author":"roda_u","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"roda_u"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/#article","isPartOf":{"@id":"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/"},"author":{"name":"roda_u","@id":"https:\/\/www.rodaonline.com\/it\/#\/schema\/person\/127511466861ea0a94826191fb005d47"},"headline":"Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d","datePublished":"2025-04-14T15:15:52+00:00","dateModified":"2025-04-23T07:36:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/"},"wordCount":11,"articleSection":["Eventi","Novit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/","url":"https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/","name":"Salone del Mobile 2025: Una passeggiata tra le sfumature della \u201cCasa Giardino\u201d - Roda","isPartOf":{"@id":"https:\/\/www.rodaonline.com\/it\/#website"},"datePublished":"2025-04-14T15:15:52+00:00","dateModified":"2025-04-23T07:36:34+00:00","author":{"@id":"https:\/\/www.rodaonline.com\/it\/#\/schema\/person\/127511466861ea0a94826191fb005d47"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rodaonline.com\/it\/novita\/salone-del-mobile-2025-una-passeggiata-tra-le-sfumature-della-casa-giardino\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.rodaonline.com\/it\/#website","url":"https:\/\/www.rodaonline.com\/it\/","name":"Roda","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rodaonline.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rodaonline.com\/it\/#\/schema\/person\/127511466861ea0a94826191fb005d47","name":"roda_u"}]}},"_links":{"self":[{"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/posts\/39133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/users\/10808"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/comments?post=39133"}],"version-history":[{"count":7,"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/posts\/39133\/revisions"}],"predecessor-version":[{"id":39373,"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/posts\/39133\/revisions\/39373"}],"wp:attachment":[{"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/media?parent=39133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/categories?post=39133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rodaonline.com\/it\/wp-json\/wp\/v2\/tags?post=39133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}